{"id":1506,"date":"2026-04-29T20:52:37","date_gmt":"2026-04-29T20:52:37","guid":{"rendered":"https:\/\/Key%20HR.osdevlabs.com\/?page_id=1506"},"modified":"2026-05-05T19:48:40","modified_gmt":"2026-05-05T19:48:40","slug":"broker-submission","status":"publish","type":"page","link":"https:\/\/keyhr2.osdevlabs.com\/es\/broker-submission\/","title":{"rendered":"Presentaci\u00f3n del corredor"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1506\" class=\"elementor elementor-1506\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6fc2869 e-flex e-con-boxed e-con e-parent\" data-id=\"6fc2869\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5726ac6 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5726ac6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">FORMS<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c007f2 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"9c007f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prospect Submission<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f3fb5a elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4f3fb5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tKey HR\u00a0provides end-to-end staffing and workforce solutions to support business hiring needs across multiple industries.\u00a0\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99e7547 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"99e7547\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/keyhr2.osdevlabs.com\/es\/contact-us\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fal fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Talk to an Expert<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-22d57d3 e-flex e-con-boxed e-con e-parent\" data-id=\"22d57d3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5683c70 e-con-full e-flex e-con e-child\" data-id=\"5683c70\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aceb92b elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"aceb92b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Get Started with Your FREE Key HR Quote Today!<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6ea2d3 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a6ea2d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Please complete the information below so that our team can begin preparing a customized quote for your client.<\/p><p>If you have any questions or would like to speak with one of our associates right away, please call us at <strong><span style=\"color: #e63946;\">800.922.4133.<\/span><\/strong>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de7289b elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"de7289b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Brokers, let\u2019s start with\u00a0your information\u00a0below.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dff389a elementor-widget__width-inherit fluentform-widget-submit-button-right fluent-form-widget-step-header-yes fluentform-widget-submit-button-custom elementor-widget elementor-widget-fluent-form-widget\" data-id=\"dff389a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"fluent-form-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n            <div class=\"fluentform-widget-wrapper fluentform-widget-custom-radio-checkbox fluentform-widget-align-default\">\n\n            \n            <div class='fluentform ff-default fluentform_wrapper_6 ffs_default_wrap'><form data-form_id=\"6\" id=\"fluentform_6\" class=\"frm-fluent-form fluent_form_6 ff-el-form-top ff_form_instance_6_1 ff-form-loading ff-form-has-steps ffs_default\" data-form_instance=\"ff_form_instance_6_1\" method=\"POST\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Broker Submission<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='1506' \/><input type=\"hidden\" id=\"_fluentform_6_fluentformnonce\" name=\"_fluentform_6_fluentformnonce\" value=\"1c1fc948a9\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/pages\/1506\" \/><div class='ff-step-container' data-name=\"step_start-6_2\" data-disable_auto_focus=\"no\" data-enable_auto_slider=\"no\" data-enable_step_data_persistency=\"no\" data-enable_step_page_resume=\"no\" data-animation_type=\"slide\" ><span class='ff_step_start'><\/span><div class='ff-step-body'><div class=\"fluentform-step active\" data-name=\"step_start-6_2\" data-disable_auto_focus=\"no\" data-enable_auto_slider=\"no\" data-enable_step_data_persistency=\"no\" data-enable_step_page_resume=\"no\" data-animation_type=\"slide\" ><div data-name=\"ff_cn_id_1\"  class='ff-t-container ff-column-container ff_columns_total_2 '><div class='ff-t-cell ff-t-column-1' style='flex-basis: 50%;'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_6_input_text_7' id='label_ff_6_input_text_7' aria-label=\"Company Name\">Company Name<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text_7\" class=\"ff-el-form-control\" placeholder=\"Enter Company Name\" data-name=\"input_text_7\" id=\"ff_6_input_text_7\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 50%;'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_6_input_text_12' id='label_ff_6_input_text_12' aria-label=\"Job Title\">Job Title<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text_12\" class=\"ff-el-form-control\" placeholder=\"Enter Your Job Title\" data-name=\"input_text_12\" id=\"ff_6_input_text_12\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><div data-type=\"name-element\" data-name=\"names_1\" class=\" ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell '><div class='ff-el-group ff-el-form-top'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_6_names_1_first_name_' id='label_ff_6_names_1_first_name_' >First Name<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names_1[first_name]\" id=\"ff_6_names_1_first_name_\" class=\"ff-el-form-control\" placeholder=\"Enter Your First Name\" aria-invalid=\"false\" aria-required=false><\/div><\/div><\/div><div class='ff-t-cell '><div class='ff-el-group ff-el-form-top'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_6_names_1_last_name_' id='label_ff_6_names_1_last_name_' >Last Name<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names_1[last_name]\" id=\"ff_6_names_1_last_name_\" class=\"ff-el-form-control\" placeholder=\"Enter Your Last Name\" aria-invalid=\"false\" aria-required=false><\/div><\/div><\/div><\/div><\/div><div data-name=\"ff_cn_id_2\"  class='ff-t-container ff-column-container ff_columns_total_2 '><div class='ff-t-cell ff-t-column-1' style='flex-basis: 50%;'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_6_phone_1' id='label_ff_6_phone_1' aria-label=\"Phone Number\">Phone Number<\/label><\/div><div class='ff-el-input--content'><input name=\"phone_1\" class=\"ff-el-form-control ff-el-phone ff_el_with_extended_validation\" type=\"tel\" placeholder=\"+1 847-221-4474\" data-name=\"phone_1\" id=\"ff_6_phone_1\" inputmode=\"tel\"  aria-invalid='false' aria-required=true><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 50%;'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_6_email_1' id='label_ff_6_email_1' aria-label=\"Email Address\">Email Address<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email_1\" id=\"ff_6_email_1\" class=\"ff-el-form-control\" placeholder=\"Enter Email Address\" data-name=\"email_1\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><div data-name=\"ff_cn_id_3\"  class='ff-t-container ff-column-container ff_columns_total_2 '><div class='ff-t-cell ff-t-column-1' style='flex-basis: 50%;'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_6_input_text_13' id='label_ff_6_input_text_13' aria-label=\"Submission: Company Name\">Submission: Company Name<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text_13\" class=\"ff-el-form-control\" placeholder=\"Enter Company Name\" data-name=\"input_text_13\" id=\"ff_6_input_text_13\"  aria-invalid=\"false\" aria-required=false><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 50%;'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_6_datetime' id='label_ff_6_datetime' aria-label=\"Desired Effective Date\">Desired Effective Date<\/label><\/div><div class='ff-el-input--content'><input  aria-label='Desired Effective Date Usa las flechas para navegar por las fechas. Pulsa Intro para seleccionar una fecha.'  aria-haspopup='dialog' data-type-datepicker data-format='m\/d\/Y' type=\"text\" name=\"datetime\" id=\"ff_6_datetime\" class=\"ff-el-form-control ff-el-datepicker\" placeholder=\"MM\/DD\/YYYY\" data-name=\"datetime\"  aria-invalid='false' aria-required=false><\/div><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label   aria-label=\"Please select which of the following services you are interested in:\">Please select which of the following services you are interested in:<\/label><\/div><div class='ff-el-input--content'><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_771a93356232fa9619154e1c504e3c74'><input  type=\"checkbox\" name=\"checkbox[]\" data-name=\"checkbox\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Payroll and Tax Administration\"  id='checkbox_771a93356232fa9619154e1c504e3c74' aria-label='Payroll and Tax Administration' aria-invalid='false' aria-required=false> <span>Payroll and Tax Administration<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_0cba0fcceafe5a06596549b8c72ff487'><input  type=\"checkbox\" name=\"checkbox[]\" data-name=\"checkbox\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Workers\u2019 Compensation Coverage\"  id='checkbox_0cba0fcceafe5a06596549b8c72ff487' aria-label='Workers\u2019 Compensation Coverage' aria-invalid='false' aria-required=false> <span>Workers\u2019 Compensation Coverage<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_dab5cebc9d2aa77ece7d2d03296a6b1c'><input  type=\"checkbox\" name=\"checkbox[]\" data-name=\"checkbox\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Employee Benefits (Medical dental, vision, 401(k) +\"  id='checkbox_dab5cebc9d2aa77ece7d2d03296a6b1c' aria-label='Employee Benefits (Medical dental, vision, 401(k) +' aria-invalid='false' aria-required=false> <span>Employee Benefits (Medical dental, vision, 401(k) +<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_afb15ea957cbf35f641cad08e3d6b6f7'><input  type=\"checkbox\" name=\"checkbox[]\" data-name=\"checkbox\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Applicant Tracking System\"  id='checkbox_afb15ea957cbf35f641cad08e3d6b6f7' aria-label='Applicant Tracking System' aria-invalid='false' aria-required=false> <span>Applicant Tracking System<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_7c2c5c598995ed7007782945c67e70ea'><input  type=\"checkbox\" name=\"checkbox[]\" data-name=\"checkbox\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Timekeeping and\/or Scheduling System\"  id='checkbox_7c2c5c598995ed7007782945c67e70ea' aria-label='Timekeeping and\/or Scheduling System' aria-invalid='false' aria-required=false> <span>Timekeeping and\/or Scheduling System<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_3e7f64d141f4fef5b06f770992ee43d3'><input  type=\"checkbox\" name=\"checkbox[]\" data-name=\"checkbox\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"Learning Management or Performance Managemen\"  id='checkbox_3e7f64d141f4fef5b06f770992ee43d3' aria-label='Learning Management or Performance Managemen' aria-invalid='false' aria-required=false> <span>Learning Management or Performance Managemen<\/span><\/label><\/div><\/div><\/div><div class='step-nav ff_step_nav_last'><button style='float: left;'  type='button' data-action='prev' class='ff-btn ff-btn-prev ff-btn-secondary' aria-label='Previous'>Previous<\/button><button style='float: right;'  type='button' data-action='next' class='ff-float-right ff-btn ff-btn-next ff-btn-secondary' aria-label='Next'>Next<\/button><\/div><\/div><div style='display: none;' class=\" fluentform-step\" data-name=\"form_step-6_1\" ><div data-name=\"ff_cn_id_4\"  class='ff-t-container ff-column-container ff_columns_total_2 '><div class='ff-t-cell ff-t-column-1' style='flex-basis: 50%;'><div class='ff-el-group  ff-dropzone'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_6_file-upload_1' id='label_ff_6_file-upload_1' aria-label=\"Upload the last 3 years of currently valued loss runs.\u00a0If there was no prior coverage, please upload a Loss History Affidavit.\">Upload the last 3 years of currently valued loss runs.\u00a0If there was no prior coverage, please upload a Loss History Affidavit.<\/label><\/div><div class='ff-el-input--content'><label for='ff_6_file-upload_1' class='ff_file_upload_holder'><span class='ff_upload_btn ff-btn' tabindex='0'>File Upload Clarification (PDF, DOC, DOCX)<\/span> <input type=\"file\" name=\"file-upload\" id=\"ff_6_file-upload_1\" class=\"ff-el-form-control  ff-screen-reader-element\" data-name=\"file-upload\" multiple=\"1\"  aria-invalid='false' aria-required=false><\/label><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 50%;'><div class='ff-el-group  ff-dropzone'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_6_file-upload_1_1' id='label_ff_6_file-upload_1_1' aria-label=\"If you have a\u00a0payroll register, dec page, narrative or other supporting documents,\u00a0please upload them here.\u00a0\">If you have a\u00a0payroll register, dec page, narrative or other supporting documents,\u00a0please upload them here.\u00a0<\/label><\/div><div class='ff-el-input--content'><label for='ff_6_file-upload_1_1' class='ff_file_upload_holder'><span class='ff_upload_btn ff-btn' tabindex='0'>File Upload Clarification (PDF, DOC, DOCX)<\/span> <input type=\"file\" name=\"file-upload_1\" id=\"ff_6_file-upload_1_1\" class=\"ff-el-form-control  ff-screen-reader-element\" data-name=\"file-upload_1\" multiple=\"1\"  aria-invalid='false' aria-required=false><\/label><\/div><\/div><\/div><\/div><div data-name=\"ff_cn_id_5\"  class='ff-t-container ff-column-container ff_columns_total_2 '><div class='ff-t-cell ff-t-column-1' style='flex-basis: 50%;'><div class='ff-el-group  ff-dropzone'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_6_file-upload_2_1' id='label_ff_6_file-upload_2_1' aria-label=\"If this prospect is a staffing company, please upload the\u00a0staffing supplemental form and end client list here.\">If this prospect is a staffing company, please upload the\u00a0staffing supplemental form and end client list here.<\/label><\/div><div class='ff-el-input--content'><label for='ff_6_file-upload_2_1' class='ff_file_upload_holder'><span class='ff_upload_btn ff-btn' tabindex='0'>File Upload Clarification (PDF, DOC, DOCX)<\/span> <input type=\"file\" name=\"file-upload_2\" id=\"ff_6_file-upload_2_1\" class=\"ff-el-form-control  ff-screen-reader-element\" data-name=\"file-upload_2\" multiple=\"1\"  aria-invalid='false' aria-required=false><\/label><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 50%;'><div class='ff-el-group  ff-dropzone'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_6_file-upload_3_1' id='label_ff_6_file-upload_3_1' aria-label=\"If you are requesting a benefits quote\u00a0please provide all benefits documents here (detailed census, current plan designs, etc.)\">If you are requesting a benefits quote\u00a0please provide all benefits documents here (detailed census, current plan designs, etc.)<\/label><\/div><div class='ff-el-input--content'><label for='ff_6_file-upload_3_1' class='ff_file_upload_holder'><span class='ff_upload_btn ff-btn' tabindex='0'>File Upload Clarification (PDF, DOC, DOCX)<\/span> <input type=\"file\" name=\"file-upload_3\" id=\"ff_6_file-upload_3_1\" class=\"ff-el-form-control  ff-screen-reader-element\" data-name=\"file-upload_3\" multiple=\"1\"  aria-invalid='false' aria-required=false><\/label><\/div><\/div><\/div><\/div><div class='ff-el-group  ff-dropzone'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_6_file-upload_4_1' id='label_ff_6_file-upload_4_1' aria-label=\"Upload the completed ACORD form here.\">Upload the completed ACORD form here.<\/label><\/div><div class='ff-el-input--content'><label for='ff_6_file-upload_4_1' class='ff_file_upload_holder'><span class='ff_upload_btn ff-btn' tabindex='0'>File Upload Clarification (PDF, DOC, DOCX)<\/span> <input type=\"file\" name=\"file-upload_4\" id=\"ff_6_file-upload_4_1\" class=\"ff-el-form-control  ff-screen-reader-element\" data-name=\"file-upload_4\" multiple=\"1\"  aria-invalid='false' aria-required=false><\/label><\/div><\/div><div class='ff-el-group    ff-el-input--content'><div class='ff-el-form-check ff-el-tc'><label aria-label='I have read and accept the Terms and Conditions and the processing of my data in accordance with the Privacy Policy' class='ff-el-form-check-label ff_tc_label' for=terms-n-condition_58afc2d8efdb3e1b5e1131793264fa9a><span class='ff_tc_checkbox'><input type=\"checkbox\" name=\"terms-n-condition\" class=\"ff-el-form-check-input\" data-name=\"terms-n-condition\" id=\"terms-n-condition_58afc2d8efdb3e1b5e1131793264fa9a\"  value='on' aria-invalid='false' aria-required=true><\/span> <div class='ff_t_c'><p>I have read and accept the Terms and Conditions and the processing of my data in accordance with the Privacy Policy<\/p><\/div><\/label><\/div><\/div>        <div class=\"ff-step-t-container ff-inner_submit_container ff-column-container ff_columns_total_2\">\n            <div class=\"ff-t-cell ff-t-column-1\"><div class='step-nav ff_step_nav_last'><button style='float: left;'  type='button' data-action='prev' class='ff-btn ff-btn-prev ff-btn-secondary' aria-label='Previous'>Previous<\/button><\/div><\/div>\n            <div class=\"ff-t-cell ff-t-column-2\">\n                <div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-lg ff_btn_style\"  aria-label=\"Submit\">Submit<\/button><\/div>            <\/div>\n        <\/div>\n        <\/div><\/div><\/div>\n        <\/fieldset><\/form><div id='fluentform_6_errors' class='ff-errors-in-stack ff_form_instance_6_1 ff-form-loading_errors ff_form_instance_6_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_6_1 = {\"id\":\"6\",\"ajaxUrl\":\"https:\\\/\\\/keyhr2.osdevlabs.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"asteriskPlacement\":\"asterisk-right\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"cssClassName\":\"\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_6_1\",\"form_id_selector\":\"fluentform_6\",\"rules\":{\"input_text_7\":{\"required\":{\"value\":true,\"message\":\"Este campo es obligatorio\",\"global_message\":\"This field is required\",\"global\":true}},\"input_text_12\":{\"required\":{\"value\":true,\"message\":\"Este campo es obligatorio\",\"global_message\":\"This field is required\",\"global\":true}},\"names_1[first_name]\":{\"required\":{\"value\":false,\"message\":\"Este campo es obligatorio\",\"global_message\":\"This field is required\",\"global\":true}},\"names_1[middle_name]\":{\"required\":{\"value\":false,\"message\":\"Este campo es obligatorio\",\"global_message\":\"This field is required\",\"global\":true}},\"names_1[last_name]\":{\"required\":{\"value\":false,\"message\":\"Este campo es obligatorio\",\"global_message\":\"This field is required\",\"global\":true}},\"phone_1\":{\"required\":{\"value\":true,\"global\":true,\"message\":\"Este campo es obligatorio\",\"global_message\":\"This field is required\"},\"valid_phone_number\":{\"value\":true,\"global\":true,\"message\":\"El n\\u00famero de tel\\u00e9fono no es v\\u00e1lido \",\"global_message\":\"Phone number is not valid\"}},\"email_1\":{\"required\":{\"value\":true,\"message\":\"Este campo es obligatorio\",\"global_message\":\"This field is required\",\"global\":true},\"email\":{\"value\":true,\"message\":\"Este campo debe contener un correo electr\\u00f3nico v\\u00e1lido\",\"global_message\":\"This field must contain a valid email\",\"global\":true}},\"input_text_13\":{\"required\":{\"value\":false,\"message\":\"Este campo es obligatorio\",\"global_message\":\"This field is required\",\"global\":true}},\"datetime\":{\"required\":{\"value\":false,\"message\":\"Este campo es obligatorio\",\"global_message\":\"This field is required\",\"global\":true}},\"checkbox\":{\"required\":{\"value\":false,\"message\":\"Este campo es obligatorio\",\"global_message\":\"This field is required\",\"global\":true}},\"file-upload\":{\"required\":{\"value\":false,\"message\":\"Este campo es obligatorio\",\"global_message\":\"This field is required\",\"global\":true},\"max_file_size\":{\"value\":null,\"message\":\"La validaci\\u00f3n falla por el tama\\u00f1o m\\u00e1ximo de archivo\",\"global_message\":\"Validation fails for maximum file size\",\"global\":true},\"max_file_count\":{\"value\":\"5\",\"message\":\"La validaci\\u00f3n falla para el recuento m\\u00e1ximo de archivos\",\"global_message\":\"Validation fails for maximum file count\",\"global\":true},\"allowed_file_types\":{\"value\":[\"pdf\",\"doc|ppt|pps|xls|mdb|docx|xlsx|pptx|odt|odp|ods|odg|odc|odb|odf|rtf|txt\",\"jpg|jpeg|gif|png|bmp\"],\"message\":\"Tipo de archivo no v\\u00e1lido\",\"global_message\":\"Invalid file type\",\"global\":true}},\"file-upload_1\":{\"required\":{\"value\":false,\"message\":\"Este campo es obligatorio\",\"global_message\":\"This field is required\",\"global\":true},\"max_file_size\":{\"value\":null,\"message\":\"La validaci\\u00f3n falla por el tama\\u00f1o m\\u00e1ximo de archivo\",\"global_message\":\"Validation fails for maximum file size\",\"global\":true},\"max_file_count\":{\"value\":\"5\",\"message\":\"La validaci\\u00f3n falla para el recuento m\\u00e1ximo de archivos\",\"global_message\":\"Validation fails for maximum file count\",\"global\":true},\"allowed_file_types\":{\"value\":[\"pdf\",\"doc|ppt|pps|xls|mdb|docx|xlsx|pptx|odt|odp|ods|odg|odc|odb|odf|rtf|txt\",\"jpg|jpeg|gif|png|bmp\"],\"message\":\"Tipo de archivo no v\\u00e1lido\",\"global_message\":\"Invalid file type\",\"global\":true}},\"file-upload_2\":{\"required\":{\"value\":false,\"message\":\"Este campo es obligatorio\",\"global_message\":\"This field is required\",\"global\":true},\"max_file_size\":{\"value\":null,\"message\":\"La validaci\\u00f3n falla por el tama\\u00f1o m\\u00e1ximo de archivo\",\"global_message\":\"Validation fails for maximum file size\",\"global\":true},\"max_file_count\":{\"value\":\"5\",\"message\":\"La validaci\\u00f3n falla para el recuento m\\u00e1ximo de archivos\",\"global_message\":\"Validation fails for maximum file count\",\"global\":true},\"allowed_file_types\":{\"value\":[\"pdf\",\"doc|ppt|pps|xls|mdb|docx|xlsx|pptx|odt|odp|ods|odg|odc|odb|odf|rtf|txt\",\"jpg|jpeg|gif|png|bmp\"],\"message\":\"Tipo de archivo no v\\u00e1lido\",\"global_message\":\"Invalid file type\",\"global\":true}},\"file-upload_3\":{\"required\":{\"value\":false,\"message\":\"Este campo es obligatorio\",\"global_message\":\"This field is required\",\"global\":true},\"max_file_size\":{\"value\":null,\"message\":\"La validaci\\u00f3n falla por el tama\\u00f1o m\\u00e1ximo de archivo\",\"global_message\":\"Validation fails for maximum file size\",\"global\":true},\"max_file_count\":{\"value\":\"5\",\"message\":\"La validaci\\u00f3n falla para el recuento m\\u00e1ximo de archivos\",\"global_message\":\"Validation fails for maximum file count\",\"global\":true},\"allowed_file_types\":{\"value\":[\"pdf\",\"doc|ppt|pps|xls|mdb|docx|xlsx|pptx|odt|odp|ods|odg|odc|odb|odf|rtf|txt\",\"jpg|jpeg|gif|png|bmp\"],\"message\":\"Tipo de archivo no v\\u00e1lido\",\"global_message\":\"Invalid file type\",\"global\":true}},\"file-upload_4\":{\"required\":{\"value\":false,\"message\":\"Este campo es obligatorio\",\"global_message\":\"This field is required\",\"global\":true},\"max_file_size\":{\"value\":null,\"message\":\"La validaci\\u00f3n falla por el tama\\u00f1o m\\u00e1ximo de archivo\",\"global_message\":\"Validation fails for maximum file size\",\"global\":true,\"_valueFrom\":\"MB\"},\"max_file_count\":{\"value\":\"5\",\"message\":\"La validaci\\u00f3n falla para el recuento m\\u00e1ximo de archivos\",\"global_message\":\"Validation fails for maximum file count\",\"global\":true},\"allowed_file_types\":{\"value\":[\"pdf\",\"doc|ppt|pps|xls|mdb|docx|xlsx|pptx|odt|odp|ods|odg|odc|odb|odf|rtf|txt\",\"jpg|jpeg|gif|png|bmp\"],\"message\":\"Tipo de archivo no v\\u00e1lido\",\"global_message\":\"Invalid file type\",\"global\":true}},\"terms-n-condition\":{\"required\":{\"value\":true,\"message\":\"Este campo es obligatorio\",\"global_message\":\"This field is required\",\"global\":true}}},\"debounce_time\":300,\"file_upload_settings\":[]};\n                            <\/script>\n                        <\/div>\n\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>FORMS Prospect Submission Key HR\u00a0provides end-to-end staffing and workforce solutions to support business hiring needs across multiple industries.\u00a0 Talk to an Expert Get Started with Your FREE Key HR Quote Today! Please complete the information below so that our team can begin preparing a customized quote for your client. If you have any questions or [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1506","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/keyhr2.osdevlabs.com\/es\/wp-json\/wp\/v2\/pages\/1506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keyhr2.osdevlabs.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/keyhr2.osdevlabs.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/keyhr2.osdevlabs.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/keyhr2.osdevlabs.com\/es\/wp-json\/wp\/v2\/comments?post=1506"}],"version-history":[{"count":12,"href":"https:\/\/keyhr2.osdevlabs.com\/es\/wp-json\/wp\/v2\/pages\/1506\/revisions"}],"predecessor-version":[{"id":2712,"href":"https:\/\/keyhr2.osdevlabs.com\/es\/wp-json\/wp\/v2\/pages\/1506\/revisions\/2712"}],"wp:attachment":[{"href":"https:\/\/keyhr2.osdevlabs.com\/es\/wp-json\/wp\/v2\/media?parent=1506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}